{"id":13800,"date":"2025-02-04T16:09:59","date_gmt":"2025-02-04T16:09:59","guid":{"rendered":"https:\/\/www.devon.gov.uk\/workingfordevon\/?page_id=13800"},"modified":"2026-03-04T10:07:50","modified_gmt":"2026-03-04T10:07:50","slug":"childrens-homes","status":"publish","type":"page","link":"https:\/\/www.devon.gov.uk\/workingfordevon\/work-in\/support-services-for-young-people\/childrens-homes\/","title":{"rendered":"Children&#8217;s Homes"},"content":{"rendered":"<p><span data-teams=\"true\">Devon County Councils Children\u2019s Homes team provide individualised support for children and young people with complex needs.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Devon County Councils Children\u2019s Homes team provide individualised support for children and young people with complex needs.<\/p>\n","protected":false},"author":2625,"featured_media":0,"parent":14173,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-13800","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:18:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.devon.gov.uk\/workingfordevon\/wp-json\/wp\/v2\/pages\/13800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devon.gov.uk\/workingfordevon\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.devon.gov.uk\/workingfordevon\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.devon.gov.uk\/workingfordevon\/wp-json\/wp\/v2\/users\/2625"}],"replies":[{"embeddable":true,"href":"https:\/\/www.devon.gov.uk\/workingfordevon\/wp-json\/wp\/v2\/comments?post=13800"}],"version-history":[{"count":8,"href":"https:\/\/www.devon.gov.uk\/workingfordevon\/wp-json\/wp\/v2\/pages\/13800\/revisions"}],"predecessor-version":[{"id":16812,"href":"https:\/\/www.devon.gov.uk\/workingfordevon\/wp-json\/wp\/v2\/pages\/13800\/revisions\/16812"}],"up":[{"embeddable":true,"href":"https:\/\/www.devon.gov.uk\/workingfordevon\/wp-json\/wp\/v2\/pages\/14173"}],"wp:attachment":[{"href":"https:\/\/www.devon.gov.uk\/workingfordevon\/wp-json\/wp\/v2\/media?parent=13800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}